{"id":1317,"date":"2022-12-14T13:02:55","date_gmt":"2022-12-14T12:02:55","guid":{"rendered":"http:\/\/www.hotelsplendid.info\/?page_id=1317"},"modified":"2026-02-23T15:57:46","modified_gmt":"2026-02-23T14:57:46","slug":"camere","status":"publish","type":"page","link":"https:\/\/www.hotelsplendid.info\/en\/camere\/","title":{"rendered":"Rooms"},"content":{"rendered":"<div class=\"g--bkg-light-01\">\n\n\n<section class=\"wao-blocks-container container-fluid mb-0 p-0 g--bkg-light-01\"\n\t\t>\n    \n<div class=\"wao-blocks-row row p-0 m-0\" >\n    \n\n<div class=\"col-12 col-md-12 p-0 m-0 position-relative\"\n     \n\t \n\t>\n        \n\n<div id=\"flc-carousel\" data-cellAlign=\"center\" data-bgLazyLoad=\"1\" data-freeScroll=\"true\" data-wrapAround=\"true\" data-autoPlay=\"2000\" data-pauseAutoPlayOnHover =\"true\" data-prevNextButtons=\"false\" data-contain=\"true\" data-pageDots=\"false\" data-draggable=\"false\" data-groupCells=\"1\" data-fade=\"false\" class=\"js--flickity wao-blocks-slider slider-top flc-carousel-5052\"  >\n\n                            <div class=\"w-100\">\n                    \n    <div style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/top-camere-splendid.jpg)center center rgba(56, 38, 30, 0.5); background-blend-mode: multiply; background-size: cover; height: 65vh; background-position: 50% 50%;' class='wao-blocks-flc-banner'>\n        <div \n            class='carousel-caption mobile-tablet-centered text-center' \n                        style='max-width: 500px; bottom: 5%; background-color:  ; margin:  auto            '>\n                    <\/div>\n        <style>\n            @media screen and (max-width: 992px) {\n                .mobile-tablet-centered {\n                    margin: auto !important;\n                }\n            }\n        <\/style>\n    <\/div>\n    \n                <\/div>\n            \n<\/div>\n\n<div class=\"position-absolute l--top d-none d-md-flex align-items-center justify-content-start l--left z-index-10 w-100 h-100\">\n<span class=\"h1 text-white text-italic pl-5 py-4 border-bottom-4px g--b-c-02 text-right \">Sogni e relax<\/span>\n<\/div>\n    <\/div>\n<\/div>\n<\/section>\n\n<section class=\"wao-blocks-container container-fluid mb-0 d-flex align-items-center justify-content-center g--bkg-light-01\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12 px-5 pt-4 pb-5\"\n     \n\t \n\t>\n        \n<div class=\" mx-auto\" style=\"max-width:1024px;\">\n\n\n<div class=\"breadcrumb-block p-3\"\n    >\n    <div class=\"text-primary mx-auto text-center small font-weight-bold\">\n        <a href=\"https:\/\/www.hotelsplendid.info\/en\" rel=\"nofollow\" title=\"Home\">Home ><\/a>\n        Camere    <\/div>\n<\/div>\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">Tre tipologie di camere<\/h1>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center h3 pb-4 m-0 text-uppercase\">Scegli la tua preferita<\/h2>\n\n\n<hr class=\"mt-0 mb-4 hr-personalizzata\">\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Le camere dello Splendid sono studiate per regalarti la<strong> massima comodit\u00e0<\/strong>, grazie agli spazi pratici e luminosi che si adattano alle esigenze di tutti. <strong>Suddivise in tre tipologie<\/strong>, tutte le stanze sono dotate di balcone, aria condizionata, Wi-Fi e tanto altro.<\/p>\n\n\n<\/div>\n    <\/div>\n<\/div>\n<\/section>\n\n<section class=\"wao-blocks-container container-fluid mb-0 px-5 pb-5\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12 col-lg-6 col-xl-5 p-0 order-lg-1 order-2\"\n     \n\t \n\t>\n        \n<div class=\"p-4 g--bkg-light-01 w-100 h-100 boxborder-l60\" >\n\n\n<h2 class=\"wp-block-heading has-text-align-left h1\">Camere Standard<\/h2>\n\n\n<hr class=\"mt-0 hr-personalizzata\">\n\n\n<p class=\"wp-block-paragraph\">Le camere Standard sono la soluzione ideale per chi cerca una<strong> sistemazione semplice e comoda<\/strong>, senza rinunciare ai servizi e alla qualit\u00e0 del riposo.\u00a0Le nostre Camere Standard sono dotate di:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>servizi privati<\/li>\n\n\n\n<li>balcone<\/li>\n\n\n\n<li>tv satellitare<\/li>\n\n\n\n<li>wi-fi<\/li>\n\n\n\n<li>telefono<\/li>\n\n\n\n<li>cassaforte<\/li>\n\n\n\n<li>aria condizionata<\/li>\n<\/ul>\n\n\n<\/div>\n    <\/div>\n\n\n<div class=\"col-12 col-lg-5 p-0 order-lg-2 order-1\"\n     \n\t \n\t>\n        \n\n<div class=\"js--flickity wao-blocks-img-carousel-flickity w-100 h-100 gallery-slider  img-carousel-flickity-244\"\n    data-cof=\"true\" data-cof-rule=\"min-height, 400px, 400px, 400px, 500px, 500px\"     data-cellAlign=\"right\" data-bgLazyLoad=\"1\" data-freeScroll=\"false\" data-wrapAround=\"true\" data-autoPlay=\"2000\" data-pauseAutoPlayOnHover =\"true\" data-prevNextButtons=\"true\" data-contain=\"true\" data-pageDots=\"false\" data-draggable=\"true\" data-initialIndex=\"1\"     >\n                <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/standard-splendid-001.jpg\" rel=\"ilightBoxstandard\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/standard-splendid-001-1024x683.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n                        <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/standard-splendid-003.jpg\" rel=\"ilightBoxstandard\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/standard-splendid-003-1024x683.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n                        <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/standard-splendid-002.jpg\" rel=\"ilightBoxstandard\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/standard-splendid-002-1024x683.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n            <\/div>\n\n\n    <\/div>\n\n\n<div class=\"col-12 col-lg-1 col-xl-2 p-0 d-none d-lg-inline order-3\"\n     \n\t \n\t>\n        \n    <figure\n        class=\"wao-blocks-immagine-bkg h-100 w-100\"\n        style=\"background: url('http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/sfondo-merida-1024x683.png') center center \/ cover no-repeat; min-height: 400px;\"\n        >\n            <\/figure>\n\n    <\/div>\n<\/div>\n<\/section>\n\n<section class=\"wao-blocks-container container-fluid mb-5 px-5\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12 col-lg-6 col-xl-5 p-0 order-lg-3 order-2\"\n     \n\t \n\t>\n        \n<div class=\"p-4 g--bkg-light-01 w-100 h-100 boxborder-r60\" >\n\n\n<h2 class=\"wp-block-heading has-text-align-left h1\">Camere vista mare\u00a0<\/h2>\n\n\n<hr class=\"mt-0 hr-personalizzata\">\n\n\n<p class=\"wp-block-paragraph\">Confortevoli come le camere Standard, ma <strong>con una coccola in pi\u00f9<\/strong>: la vista del mare da ammirare ogni giorno dal tuo balcone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Queste camere si trovano nella<strong> facciata laterale dell\u2019hotel<\/strong> e dispongono di:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>servizi privati<\/li>\n\n\n\n<li>balcone<\/li>\n\n\n\n<li>tv satellitare<\/li>\n\n\n\n<li>wi-fi<\/li>\n\n\n\n<li>telefono<\/li>\n\n\n\n<li>cassaforte<\/li>\n\n\n\n<li>aria condizionata<\/li>\n\n\n\n<li>vista mare laterale<\/li>\n<\/ul>\n\n\n<\/div>\n    <\/div>\n\n\n<div class=\"col-12 col-lg-5 p-0 order-lg-2 order-1\"\n     \n\t \n\t>\n        \n\n<div class=\"js--flickity wao-blocks-img-carousel-flickity w-100 h-100 gallery-slider  img-carousel-flickity-48188\"\n    data-cof=\"true\" data-cof-rule=\"min-height, 400px, 400px, 400px, 500px, 500px\"     data-cellAlign=\"right\" data-bgLazyLoad=\"1\" data-freeScroll=\"false\" data-wrapAround=\"true\" data-autoPlay=\"2000\" data-pauseAutoPlayOnHover =\"true\" data-prevNextButtons=\"true\" data-contain=\"true\" data-pageDots=\"false\" data-draggable=\"true\" data-initialIndex=\"1\"     >\n                <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/camera-splendid-rosa.jpg\" rel=\"ilightBoxvistamare\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/camera-splendid-rosa-1024x684.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n                        <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/bagno-splendid.jpg\" rel=\"ilightBoxvistamare\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/bagno-splendid-1024x683.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n            <\/div>\n\n\n    <\/div>\n\n\n<div class=\"col-12 col-lg-1 col-xl-2 p-0 d-none d-lg-inline order-1\"\n     \n\t \n\t>\n        \n    <figure\n        class=\"wao-blocks-immagine-bkg h-100 w-100\"\n        style=\"background: url('http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/sfondo-merida-1024x683.png') center center \/ cover no-repeat; min-height: 400px;\"\n        >\n            <\/figure>\n\n    <\/div>\n<\/div>\n<\/section>\n\n<section class=\"wao-blocks-container container-fluid mb-0 px-5 pb-5\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12 col-lg-6 col-xl-5 p-0 order-lg-1 order-2\"\n     \n\t \n\t>\n        \n<div class=\"p-4 g--bkg-light-01 w-100 h-100 boxborder-l60\" >\n\n\n<h2 class=\"wp-block-heading has-text-align-left h1\">Camere fronte mare<\/h2>\n\n\n<hr class=\"mt-0 hr-personalizzata\">\n\n\n<p class=\"wp-block-paragraph\">Confortevoli camere dotate di tutti i servizi, sono la scelta ideale per chi vuole aggiungere un po\u2019 di magia alla vacanza con una <strong>splendida vista mare frontale<\/strong> che ti dar\u00e0 il buongiorno ogni mattina al tuo risveglio!\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le camere sono attrezzate con:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>servizi privati<\/li>\n\n\n\n<li>balcone<\/li>\n\n\n\n<li>tv satellitare<\/li>\n\n\n\n<li>wi-fi<\/li>\n\n\n\n<li>telefono<\/li>\n\n\n\n<li>cassaforte<\/li>\n\n\n\n<li>aria condizionata<\/li>\n\n\n\n<li>vista mare frontale<\/li>\n<\/ul>\n\n\n<\/div>\n    <\/div>\n\n\n<div class=\"col-12 col-lg-5 p-0 order-lg-2 order-1\"\n     \n\t \n\t>\n        \n\n<div class=\"js--flickity wao-blocks-img-carousel-flickity w-100 h-100 gallery-slider  img-carousel-flickity-32325\"\n    data-cof=\"true\" data-cof-rule=\"min-height, 400px, 400px, 400px, 500px, 500px\"     data-cellAlign=\"right\" data-bgLazyLoad=\"1\" data-freeScroll=\"false\" data-wrapAround=\"true\" data-autoPlay=\"2000\" data-pauseAutoPlayOnHover =\"true\" data-prevNextButtons=\"true\" data-contain=\"true\" data-pageDots=\"false\" data-draggable=\"true\" data-initialIndex=\"1\"     >\n                <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/fronte-mare-001.jpg\" rel=\"ilightBoxfrontemare\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/fronte-mare-001-1024x683.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n                        <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/fronte-mare-002.jpg\" rel=\"ilightBoxfrontemare\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/fronte-mare-002-1024x683.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n                        <div class=\"col-12 col-sm-12 col-md-12 p-0 h-100\">\n             <a href=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/fronte-mare-003.jpg\" rel=\"ilightBoxfrontemare\" title=\"Apri la galleria\">\n                \n                            \n                                                        <div class=\"w-100\" style='background: url(http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/fronte-mare-003-1024x683.jpg); background-size: cover; height: 100%;background-position: 50% 50%;'><\/div>\n                    <\/a>                         <\/a>     \n\n                                            <\/div>\n            <\/div>\n\n\n    <\/div>\n\n\n<div class=\"col-12 col-lg-1 col-xl-2 p-0 d-none d-lg-inline order-3\"\n     \n\t \n\t>\n        \n    <figure\n        class=\"wao-blocks-immagine-bkg h-100 w-100\"\n        style=\"background: url('http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/sfondo-merida-1024x683.png') center center \/ cover no-repeat; min-height: 400px;\"\n        >\n            <\/figure>\n\n    <\/div>\n<\/div>\n<\/section>\n\n<div class=\" p-5\">\n\n<section class=\"wao-blocks-container container-fluid mb-2\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12 col-lg-6 position-relative\"\n     \n\t \n\t>\n        \n<div class=\"d-lg-none d-block text-center pb-4\">\n\n\n<p class=\"has-text-align-center h1 text-tertiary wp-block-paragraph\">Direttamente sul mare<\/p>\n\n\n<\/div>\n\n<div >\n<iframe title=\"Google Map per raggiungere Hotel Splendid di Gatteo Mare\" class=\"js--lazy-load ml-5\" data-src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d11446.925849818506!2d12.4393417!3d44.1713941!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x0%3A0xff105309b708fe6c!2sHotel%20Splendid%20-%20Gatteo!5e0!3m2!1sit!2sit!4v1670430513273!5m2!1sit!2sit\" width=\"100%\" width=\"height%\" style=\"border:0;z-index:5;min-height:350px;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n<\/div>\n\n\n\n<div class=\"js--hideme  position-absolute l--bottom h-100 l--left z-index-10 z-index-10 d-none d-lg-flex align-items-end\" style=\"margin-left:-3rem;\" data-anim=\"fadeInUp\">\n<div class=\"scrittaverticale display-1 font-weight-bold text-secondary\"><span>DOVE<br>SIAMO<\/span><\/div>\n<\/div>\n    <\/div>\n\n\n<div class=\"col-12 col-md-12 col-lg-6\"\n     \n\t \n\t>\n        \n<div class=\"h-100 px-5\"><div class=\"g--bkg-light-01 p-5 h-100 \">\n\n\n<p class=\"has-text-align-center h1 wp-block-paragraph\">Newsletter<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Iscriviti per ricevere le nostre offerte e rimanere aggiornato su tutte le novit\u00e0 dell\u2019hotel.<\/p>\n\n\n<script src=\"https:\/\/www.google.com\/recaptcha\/enterprise.js?render=6LdKs-6Lc3xMIcAAAAAO2K3CkgGUYb6BcsBOk289jP7NUP\"><\/script>\n<div class=\"wao-blocks-newsletter-v2\">\n    \n<!--IMPORTANTE non cambiare il nome degli id, dei name, dei title, e la classe privacy link-privacy-policy -->\n<div class=\"l--box-newsletter\"><form id=\"iscrizione_newsletter\" class=\"custom\" autocomplete=\"OFF\" method=\"post\" name=\"iscrizione_newsletter\">\n<fieldset>\n\t<div class=\"form-group row\">\n\t\t<div class=\"col-12 col-md-6 mx-auto mb-2 px-1\"><input id=\"news_nome\" class=\"form-control text-primary rounded-0\" name=\"nome\" type=\"text\" placeholder=\"Nome*\"><\/div>\n\t\t<div class=\"col-12 col-md-6 mx-auto mb-2 px-1\"><input id=\"news_email\" class=\"form-control text-primary rounded-0\" name=\"email\" type=\"text\" value=\"\" placeholder=\"Email*\"><\/div>\n\t\t<div id=\"newsletter\" class=\"col-12 col-lg-6 mx-auto px-1\"><input id=\"news_privacy\" style=\"width: 30px; height: 30px;border:1px solid #b8ac99 !important;\" name=\"news_privacy\" type=\"checkbox\" value=\"on\">\n\t\t\t<label style=\"vertical-align: text-bottom; font-size: 20px; color: #ffffff;\" for=\"news_privacy\">\n\t\t\t\t*<small> <a class=\"privacy link-privacy-policy\" title=\"Accetta la nostra Privacy Policy\" style=\"cursor: pointer;\" title=\"privacy\">Accetto Privacy Policy<\/a><\/small>\n\t\t\t<\/label>\n\t\t<\/div>\n\t\t<div class=\"col-12 col-lg-6 px-1\">\n\t\t\t<button id=\"iscrizioneNewsletter\" class=\"btn btn-secondary btn-block d-flex align-items-center justify-content-between js--hideme\" data-anim=\"bounceIn\" title=\"Iscriviti alla newsletter\"  type=\"submit\">\n\t\t\t\tIscrivimi  <i class=\"fa fa-long-arrow-right\" aria-hidden=\"true\"><\/i>\n\t\t\t<\/button>\n\t\t\t<input name=\"dominio\" type=\"hidden\" value=\"https:\/\/www.hotelsplendid.info\/en\/\">\n\t\t\t<input name=\"idHotel\" type=\"hidden\" value=\"\">\n\t\t\t<input name=\"lingua\" type=\"hidden\" value=\"it\">\n\t\t<\/div>\n\t<\/div>\n<\/fieldset>\n<\/form>\n<\/div>\n<div id=\"divAlert\" class=\"h-50 w-50 m-auto alert-info d-none\" style=\"position: fixed; top: 10px; left: 10px; right: 10px; bottom: 10px; z-index: 2000; overflow: auto;\">\n<div class=\"text-right\"><a class=\"btn btn-primary btn_chiudi \" href=\"javascript:void(0)\" onclick=\"location.reload(true);\"><i class=\"fa fa-times\" aria-hidden=\"true\"><\/i><\/a><\/div>\n<div class=\"text-center alert-info l--align-middle-vertical\" style=\"height: calc(100% - 50px);\">\n<div class=\"logo\"><\/div>\n<div class=\"text-center h-50 w-50\"><i class=\"fa fa-paper-plane\" aria-hidden=\"true\"><\/i>\n<h4>iscrizione alla newsletter completata con successo<\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div>\n    <\/div>\n<\/div>\n<\/section>\n\n<\/div>\n\n<section class=\"wao-blocks-container container-fluid mb-0 g--bkg-light-02\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12\"\n     \n\t \n\t>\n        \n<div class=\"px-4 py-5\">\n\n\n<p class=\"has-text-align-center h1 wp-block-paragraph\">Punti Forza<\/p>\n\n\n\n<p class=\"has-text-align-center font-weight-bold h3 text-uppercase wp-block-paragraph\">TUTTO QUELLO CHE DESIDERI<\/p>\n\n\n<hr class=\"mt-0 hr-personalizzata\">\n\n<\/div>\n<div class=\"mx-auto\" style=\"max-width:1280px;\">\n\n<div id=\"innerblocks-slider-parent1\" data-wrapAround='false' data-cellAlign=\"right\" data-bgLazyLoad=\"1\" data-freeScroll=\"false\" data-autoPlay=\"5000\" data-pauseAutoPlayOnHover =\"true\" data-prevNextButtons=\"false\" data-contain=\"true\" data-pageDots=\"false\" data-draggable=\"true\"  class=\"wrap-desktop js--flickity wao-blocks-slider innerblocks-slider-parent-64083 no-drag-fix-innerblocks-slider-parent-64083 \"  >\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-lg-left\">\n<figure class=\"thumbnail_primopiano mleft-47px\" style=\"margin-bottom:-20px;z-index:10\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/vista-mare-splendid-2022.jpg\" alt=\"Hotel sul mare\" class=\"img-fluid mr-auto max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza ml-3 text-center text-uppercase text-tertiary font-weight-bold\">DIRETTAMENTE<br\/>SUL MARE<\/div>\n<\/div>\n\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n\n        <\/div>\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-center\">\n<figure class=\"thumbnail_primopiano mbottom-47px\" style=\"z-index:10;\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/reception-splendid-2022.jpg\" alt=\"Gestione famigliare da 60 anni\" class=\"img-fluid mx-auto max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza mx-3 text-center  text-uppercase text-tertiary font-weight-bold\">GESTIONE FAMIGLIARE<br\/>DA 60 ANNI<\/div>\n<\/div>\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n\n        <\/div>\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-center\">\n<figure class=\"thumbnail_primopiano\" style=\"margin-bottom:-20px;z-index:10\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/chef-splendid-2022.jpg\" alt=\"Cucina casalinga\" class=\"img-fluid mx-auto max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza  mx-3 text-center  text-uppercase text-tertiary font-weight-bold\">CUCINA<br\/>CASALINGA<\/div>\n<\/div>\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n\n        <\/div>\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-lg-right\">\n<figure class=\"thumbnail_primopiano\" style=\"margin-left:20px;margin-bottom:-20px;z-index:10;\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/camera-fronte-mare-splendid.jpg\" alt=\"Camere con vista mare\" class=\"img-fluid ml-auto mr-0 max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza mr-3 text-center text-uppercase text-tertiary font-weight-bold\">CAMERE CON<br\/>VISTA MARE<\/div>\n<\/div>\n\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n        <\/div>\n    <\/div>\n<div id=\"innerblocks-slider-parent2\"  data-wrapAround='true' data-cellAlign=\"right\" data-bgLazyLoad=\"1\" data-freeScroll=\"false\" data-autoPlay=\"5000\" data-pauseAutoPlayOnHover =\"true\" data-prevNextButtons=\"false\" data-contain=\"true\" data-pageDots=\"false\" data-draggable=\"true\" class=\"wrap-mobile js--flickity wao-blocks-slider innerblocks-slider-parent-64083\"  >\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-lg-left\">\n<figure class=\"thumbnail_primopiano mleft-47px\" style=\"margin-bottom:-20px;z-index:10\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/vista-mare-splendid-2022.jpg\" alt=\"Hotel sul mare\" class=\"img-fluid mr-auto max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza ml-3 text-center text-uppercase text-tertiary font-weight-bold\">DIRETTAMENTE<br\/>SUL MARE<\/div>\n<\/div>\n\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n\n        <\/div>\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-center\">\n<figure class=\"thumbnail_primopiano mbottom-47px\" style=\"z-index:10;\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/reception-splendid-2022.jpg\" alt=\"Gestione famigliare da 60 anni\" class=\"img-fluid mx-auto max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza mx-3 text-center  text-uppercase text-tertiary font-weight-bold\">GESTIONE FAMIGLIARE<br\/>DA 60 ANNI<\/div>\n<\/div>\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n\n        <\/div>\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-center\">\n<figure class=\"thumbnail_primopiano\" style=\"margin-bottom:-20px;z-index:10\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/chef-splendid-2022.jpg\" alt=\"Cucina casalinga\" class=\"img-fluid mx-auto max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza  mx-3 text-center  text-uppercase text-tertiary font-weight-bold\">CUCINA<br\/>CASALINGA<\/div>\n<\/div>\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n\n        <\/div>\n            <div class=\"col-12 col-md-6 col-lg-3 p-0\" style=\"height:500px\">\n            \n    <div \n        class='innerblocks-slider-child wao-blocks-innerblocks-slider-child' \n        >\n        \n<div class=\"p-4 text-lg-right\">\n<figure class=\"thumbnail_primopiano\" style=\"margin-left:20px;margin-bottom:-20px;z-index:10;\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/camera-fronte-mare-splendid.jpg\" alt=\"Camere con vista mare\" class=\"img-fluid ml-auto mr-0 max-w-285px\"><\/figure>\n<div class=\"g--bkg-dark-01 px-3 pb-4 pt-forza mr-3 text-center text-uppercase text-tertiary font-weight-bold\">CAMERE CON<br\/>VISTA MARE<\/div>\n<\/div>\n\n    <\/div>\n    <style>\n        @media screen and (max-width: 992px) {\n            .innerblocks-slider-child {\n                margin: auto !important;\n            }\n        }\n    <\/style>\n  \n        <\/div>\n    <\/div>\n\n<\/div>\n    <\/div>\n<\/div>\n<\/section>\n\n<div class=\"g--bkg-light-02 text-center\">\n\n\n<section class=\"wao-blocks-container container-fluid mb-0 sf-merida\"\n\t\t>\n    \n<div class=\"wao-blocks-row row\" >\n    \n\n<div class=\"col-12 col-md-12\"\n     \n\t \n\t>\n        \n<div class=\"d-flex justify-content-center mx-auto max-width-1120\" style=\"margin-top:-45px; \">\n<div>\n<figure class=\"d-none d-lg-block m-0 p-0 max-width-1120\"><img decoding=\"async\" src=\"http:\/\/www.hotelsplendid.info\/wp-content\/uploads\/2022\/12\/top-merida-1.png\" class=\"img-fluid mx-auto mb-0 max-width-1120\" alt=\"Decorazione\"><\/figure>\n<div class=\"px-5 pt-2 pb-5 g--bkg-light-04 text-left\">\n<div class=\"h1 text-center mb-3 p-4\">Richiedi un preventivo gratuito<\/div>\n<div class=\"mx-auto\" style=\"max-width:850px;\">\n\n\n<div class=\"merida_root\" id=\"merida_block\"><\/div>\n\n<script>\nvar merida_config_merida_block = {\n    customerId: 1243 ,\n    showSuccessModal : true,\n    rootEl: \"merida_block\",\n    childrenAgeMax: 16,\n    childrenAgeMin: 0,\n    layout: \"compact\",\n    language: \"en\",\n                theme : {\n        colors: {\n            primary: '#a17f29',\n            primaryTextAlt: '#ffffff',\n            secondary: '#450d0d',\n            secondaryTextAlt: '#ffffff',\n            text: '#3e464c',\n            error: '#cc0033',\n            formBackground: '#ffffff',\n            label: '#4d4d4d',\n            labelInput: '#450d0d',\n            labelInputActive: '#7ebd6d',\n            inputBackground: '#ffffff',\n            inputBorder: '#b8ac99',\n            checkboxBorder: '#ffffff',\n        }\n    },\n    onSuccess : function(res) {\n        \n                        if (typeof(ga) !== 'undefined') {\n                   ga('send', 'event', 'Email', 'Invio', 'Form');\n                }\n                    }\n};\n\n(function(url, cb) {\n    var s = document.createElement(\"script\");\n    s.type = \"text\/javascript\";\n\n    if (s.readyState) { \/\/IE\n        s.onreadystatechange = function() {\n            if (s.readyState == \"loaded\" || s.readyState == \"complete\") {\n                s.onreadystatechange = null;\n                cb();\n            }\n        };\n    } else { \/\/Others\n        s.onload = function() {\n            cb();\n        };\n    }\n\n    s.src = url;\n    document.getElementsByTagName(\"head\")[0].appendChild(s);\n})(\"https:\/\/static.adriasonline.it\/merida\/latest\/merida.js\", function() {\n    window.aoForm = merida(merida_config_merida_block);\n});\n<\/script>\n\n<\/div>\n\n<\/div>\n<\/div>\n<\/div>\n    <\/div>\n<\/div>\n<\/section>\n\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1317","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/pages\/1317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/comments?post=1317"}],"version-history":[{"count":22,"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/pages\/1317\/revisions"}],"predecessor-version":[{"id":2594,"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/pages\/1317\/revisions\/2594"}],"wp:attachment":[{"href":"https:\/\/www.hotelsplendid.info\/en\/wp-json\/wp\/v2\/media?parent=1317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}